{"id":149,"date":"2015-02-08T19:16:13","date_gmt":"2015-02-08T18:16:13","guid":{"rendered":"http:\/\/hasenjagd.annakram.de\/?p=149"},"modified":"2019-03-24T21:10:34","modified_gmt":"2019-03-24T20:10:34","slug":"so-weit-so-gut","status":"publish","type":"post","link":"https:\/\/hasenjagd.annakram.de\/en\/2015\/02\/so-weit-so-gut\/","title":{"rendered":"So weit, so&nbsp;gut!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"149\" class=\"elementor elementor-149\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ed6a993 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ed6a993\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19c9ca26\" data-id=\"19c9ca26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af9c6ef elementor-widget elementor-widget-image-gallery\" data-id=\"af9c6ef\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"gallery-1\" class=\"gallery galleryid-149 gallery-columns-6 gallery-size-thumbnail\"><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af9c6ef\" data-elementor-lightbox-title=\"dsc02840\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYwLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NDAuanBnIiwic2xpZGVzaG93IjoiYWY5YzZlZiJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02840.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02840-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af9c6ef\" data-elementor-lightbox-title=\"dsc02846\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYxLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NDYuanBnIiwic2xpZGVzaG93IjoiYWY5YzZlZiJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02846.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02846-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af9c6ef\" data-elementor-lightbox-title=\"dsc02853\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU2LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NTMuanBnIiwic2xpZGVzaG93IjoiYWY5YzZlZiJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02853.jpg\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02853-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af9c6ef\" data-elementor-lightbox-title=\"dsc02855\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU3LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NTUuanBnIiwic2xpZGVzaG93IjoiYWY5YzZlZiJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02855.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02855-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af9c6ef\" data-elementor-lightbox-title=\"dsc02856\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU4LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NTYuanBnIiwic2xpZGVzaG93IjoiYWY5YzZlZiJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02856.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02856-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af9c6ef\" data-elementor-lightbox-title=\"dsc02859\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU5LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NTkuanBnIiwic2xpZGVzaG93IjoiYWY5YzZlZiJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02859.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02859-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75e3c7d elementor-widget elementor-widget-text-editor\" data-id=\"75e3c7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Wir hat\u00adten das Basis\u00adla\u00adger, die Jena\u00ader USV-Sport\u00adhal\u00adle an den Teu\u00adfels\u00adl\u00f6\u00adchern, erreicht. Der Name des Orts lie\u00df eine fana\u00adti\u00adsche Hor\u00adde Wolf\u00adgang-Petry-J\u00fcn\u00adger, die Apo\u00adka\u00adlyp\u00adse beschw\u00f6\u00adrend,&nbsp;vor mei\u00adnem inne\u00adren Auge auf\u00adtau\u00adchen. \u201cH\u00f6l\u00adle! H\u00f6l\u00adle!\u201d&nbsp;Ich hat\u00adte mich im&nbsp;Griff.<\/p><p>Knapp tau\u00adsend Sports\u00adm\u00e4n\u00adner und \u2011frau\u00aden nebst Anhang hat\u00adten sich ein\u00adge\u00adfun\u00adden.&nbsp;Das Org-Team hat\u00adte Bier\u00adgar\u00adni\u00adtu\u00adren und Unter\u00adhal\u00adtungs\u00admu\u00adsik besorgt. Ein&nbsp;paar der weni\u00adgen frei\u00aden Pl\u00e4t\u00adze konn\u00adten wir ergattern.<\/p><p>Der Gro\u00df\u00adteil hat\u00adte sich auf dem Rasen breit gemacht. Die Son\u00adne sorg\u00adte f\u00fcr ent\u00adspre\u00adchen\u00adde Stim\u00admung. Es wur\u00adde geschwatzt, gescherzt und gelacht. Wir schwiegen.<\/p><p>Mein Blick war die Kern\u00adber\u00adge hoch\u00adge\u00adkra\u00adxelt. Ich hat\u00adte mich ver\u00adsch\u00e4tzt. Die Gier auf einen ein\u00adzig\u00adar\u00adti\u00adgen Finis\u00adher-Kick hat\u00adte alle Zwei\u00adfel ver\u00addr\u00e4ngt.&nbsp;Von Anfang an.<\/p><p>Lars hat\u00adte mich nach dem Erfur\u00adter Sil\u00adves\u00adter\u00adlauf 2013 auf die Saa\u00adle-Hori\u00adzon\u00adta\u00adle ange\u00adspro\u00adchen. Er mein\u00adte den Staf\u00adfel\u00adlauf.&nbsp;Ich hat\u00adte irgend\u00adwann mal etwas von der Wan\u00adde\u00adrung geh\u00f6rt. Wan\u00adde\u00adrung? Wir nick\u00adten kurz ab. Dabei blieb es. Ehrensache!<\/p><p>Dass von mei\u00adnen ande\u00adren Lauf\u00adfreun\u00adden ein\u00adzig noch Tuti zusag\u00adte, hat\u00adte mich auch nicht wei\u00adter irri\u00adtiert. Mit feh\u00adlen\u00adder Zeit lie\u00df sich doch heut\u00adzu\u00adta\u00adge alles recht\u00adfer\u00adti\u00adgen.&nbsp;Jetzt summ\u00adten&nbsp;mei\u00adne Synapsen.<\/p><p>Ein\u00adhun\u00addert Kilo\u00adme\u00adter.&nbsp;Das w\u00e4re bei 24 Stun\u00adden Lauf\u00adzeit,&nbsp;inklu\u00adsi\u00adve Pau\u00adsen, ein Stun\u00adden\u00admit\u00adtel von 4,5 Kilo\u00adme\u00adtern.&nbsp;Mein Blick war Rich\u00adtung S\u00fcden gewan\u00addert. Ber\u00adge. Das mach\u00adte es nicht leichter.<\/p><p>Tuti hat\u00adte Bier gereicht. Ein wei\u00adser Mann. Es war sowie\u00adso der fal\u00adsche Moment, den Gang zu hin\u00adter\u00adfra\u00adgen. Nie\u00admals w\u00fcr\u00adde einer von uns Drei\u00aden jetzt einen R\u00fcck\u00adzie\u00adher machen. Prost!<\/p><p>Der Chef\u00adver\u00adan\u00adstal\u00adter hat\u00adte die anwe\u00adsen\u00adden Wan\u00adders\u00adleu\u00adte nebst Anhang begr\u00fc\u00dft. Ein wenig weh\u00adm\u00fc\u00adtig beklag\u00adte er, dass es nicht ganz tau\u00adsend Teil\u00adneh\u00admer gewor\u00adden w\u00e4ren. Immer\u00adhin 970 woll\u00adten es wissen.<\/p><p>Und dann ging es auch schon los. Ich schn\u00fcr\u00adte noch ein wenig an mei\u00adnen Schu\u00adhen her\u00adum, als sich die Wan\u00adder\u00adtrup\u00adpe in Bewe\u00adgung setzte.<\/p><p><span class=\"dquo\">\u201c<\/span>Lass die Luschen ruhig los\u00adtra\u00adben, bis Z\u00f6ll\u00adnitz haben wir die lan\u00adge wie\u00adder im&nbsp;Sack!\u201d<\/p><p>Unwill\u00adk\u00fcr\u00adlich hat\u00adte ich die Bli\u00adcke mei\u00adner Freun\u00adde gesucht. Und genau\u00adso unwill\u00adk\u00fcr\u00adlich sahen wir uns&nbsp;um.<\/p><p>Die Stre\u00adcke lock\u00adte auch Ultra\u00adl\u00ad\u00e4u\u00adfer an. Zumeist star\u00adten die\u00adse sp\u00e4\u00adter, um nicht zu fr\u00fch die Ver\u00adsor\u00adgungs\u00adstel\u00adlen, deren \u00d6ff\u00adnungs\u00adzei\u00adten sich am Tem\u00adpo der Wan\u00adders\u00adleu\u00adte ori\u00aden\u00adtie\u00adren, zu errei\u00adchen.&nbsp;Im Grun\u00adde sind sie erha\u00adben gegen\u00ad\u00fcber den weni\u00adger ambi\u00adtio\u00adnier\u00adten Sports\u00adfreun\u00adden. Wie die meis\u00adten ande\u00adren L\u00e4u\u00adfer und Wan\u00adde\u00adrer auch. Aber es gibt sie eben, die Rennpfauen.<\/p><p>Nor\u00adma\u00adler\u00adwei\u00adse gewin\u00adnen sie mir nichts mehr als ein m\u00fcdes L\u00e4cheln ab. Doch an jenem Frei\u00adtag\u00adabend im Mai tra\u00adfen sie mich auf dem fal\u00adschen Fu\u00df.&nbsp;Sie mach\u00adten es mir aber auch nicht all\u00adzu schwer, sie unsym\u00adpa\u00adthisch zu fin\u00adden.&nbsp;W\u00e4h\u00adrend der \u00c4lte\u00adre, der immer wie\u00adder an einer PET-Fla\u00adsche mit einer neon\u00adfar\u00adbi\u00adgen Fl\u00fcs\u00adsig\u00adkeit nuckel\u00adte, irgend\u00adwel\u00adche Moti\u00adva\u00adti\u00adons\u00adspr\u00fc\u00adche vor sich her\u00adbe\u00adte\u00adte, saug\u00adte der J\u00fcn\u00adge\u00adre jedes sei\u00adner Wor\u00adte bana\u00adnen\u00adm\u00adamp\u00adfend in sich&nbsp;auf.<\/p><p>Ich hat\u00adte ihnen ins\u00adge\u00adheim ein lan\u00adges, von psy\u00adchi\u00adschen Ein\u00adschr\u00e4n\u00adkun\u00adgen ver\u00adschon\u00adtes, sor\u00adgen\u00advol\u00adles Leben an den Hals gew\u00fcnscht, und mal\u00adte mir aus, wie Iso\u00adt\u00adrink\u00adfix und Bana\u00adnen\u00adbei\u00ad\u00dfer im hohen Alter in einem Alten\u00adpfle\u00adge\u00adheim in Lauf\u00aderin\u00adne\u00adrun\u00adgen schwel\u00adgen w\u00fcr\u00adden. Aber nie\u00admand w\u00fcr\u00adde ihre Geschich\u00adten mehr h\u00f6ren wol\u00adlen. L\u00e4u\u00adfer\u00adgarn aus einer Zeit, als man sich noch die Knie kaputt rann\u00adte. Die Pfle\u00adger w\u00fcr\u00adden sie wun\u00adder\u00adlich fin\u00adden und vor allem so behan\u00addeln. Sich zu weh\u00adren, w\u00e4re ange\u00adsichts ihres schw\u00e4\u00adcheln\u00adden Fleischs ein wei\u00adte\u00adrer Br\u00fcl\u00adler. Ihre lauf\u00adge\u00adst\u00e4rk\u00adten&nbsp;Her\u00adzen w\u00fcr\u00adden jedoch schla\u00adgen. Ausdauernd.<\/p><p><span class=\"dquo\">\u201c<\/span>Dann mal los, ihr Luschen!\u201d frot\u00adzel\u00adte ich. Wir tran\u00adken unser Bier aus und gin\u00adgen zum Start\u00adbe\u00adreich. Iso\u00adt\u00adrink\u00adfix und Bana\u00adnen\u00adbei\u00ad\u00dfer glotz\u00adten uns hin\u00adter\u00adher. Ich hat\u00adte mich nicht umge\u00adschaut, ich sp\u00fcr\u00adte ihre Bli\u00adcke. Sie hat\u00adten kei\u00adne Ahnung von mei\u00adnem&nbsp;Fluch.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3862afa elementor-widget elementor-widget-image-gallery\" data-id=\"3862afa\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"gallery-2\" class=\"gallery galleryid-149 gallery-columns-6 gallery-size-thumbnail\"><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3862afa\" data-elementor-lightbox-title=\"dsc02860\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY2LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NjAuanBnIiwic2xpZGVzaG93IjoiMzg2MmFmYSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02860.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02860-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3862afa\" data-elementor-lightbox-title=\"dsc02863\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY3LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NjMuanBnIiwic2xpZGVzaG93IjoiMzg2MmFmYSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02863.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02863-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3862afa\" data-elementor-lightbox-title=\"dsc02865\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY4LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NjUuanBnIiwic2xpZGVzaG93IjoiMzg2MmFmYSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02865.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02865-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon portrait\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3862afa\" data-elementor-lightbox-title=\"dsc02869\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NjkuanBnIiwic2xpZGVzaG93IjoiMzg2MmFmYSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02869.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02869-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3862afa\" data-elementor-lightbox-title=\"dsc02871\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY0LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NzEuanBnIiwic2xpZGVzaG93IjoiMzg2MmFmYSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02871.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02871-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3862afa\" data-elementor-lightbox-title=\"dsc02878\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY1LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4NzguanBnIiwic2xpZGVzaG93IjoiMzg2MmFmYSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02878.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02878-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40ee24e elementor-widget elementor-widget-text-editor\" data-id=\"40ee24e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Wir mar\u00adschier\u00adten umringt von vie\u00adlen Gleich\u00adge\u00adsinn\u00adten gen S\u00fcden. Die W\u00f6ll\u00adnit\u00adzer Stra\u00ad\u00dfen waren etwas \u00fcber\u00adfor\u00addert. Unse\u00adre Pro\u00adzes\u00adsi\u00adon muss\u00adte an engen Pas\u00adsa\u00adgen immer wie\u00adder stop\u00adpen. Die Dr\u00e4ng\u00adler hat\u00adten ihren Spa\u00df dabei und die ande\u00adren lie\u00ad\u00dfen ihnen die\u00adsen. Alles in allem wirk\u00adte es nicht wie ein Hun\u00addert-Kilo\u00adme\u00adter-Marsch. Es herrsch\u00adte Par\u00adty\u00adlau\u00adne. Es wur\u00adde viel gelacht, eini\u00adge g\u00f6nn\u00adten sich ein Bier und ein paar Meter vor uns bear\u00adbei\u00adte\u00adte ein Wan\u00adder\u00adbur\u00adsche art\u00adei\u00adgen sei\u00adne Wan\u00adder\u00adklamp\u00adfe. Blo\u00adwing in the&nbsp;wind!<\/p><p>Ich hat\u00adte mei\u00adne St\u00f6\u00adcke aus\u00adge\u00adpackt, es ging berg\u00adauf. Die Wege waren schma\u00adler gewor\u00adden. G\u00e4n\u00adse\u00admarsch war ange\u00adsagt. Wir spra\u00adchen nur noch das N\u00f6tigs\u00adte.&nbsp;Den Musi\u00adkus hat\u00adten wir hin\u00adter uns gelas\u00adsen. Irgend\u00adwann war sein Geklim\u00adper ver\u00adstummt. Die Par\u00adty war vorbei.<\/p><p>Einem Lind\u00adwurm gleich schl\u00e4n\u00adgel\u00adten wir uns durchs Gel\u00e4n\u00adde. Schrof\u00adfe fel\u00adsi\u00adge H\u00e4n\u00adge und Wild\u00adwuchs wech\u00adsel\u00adten sich ab. Zwie\u00adlicht. Stei\u00adni\u00adger Boden. Wur\u00adzeln. Nicht jeder kam mehr mit. Immer wie\u00adder stock\u00adte der Zug. Zum \u00dcber\u00adho\u00adlen muss\u00adten die Betref\u00adfen\u00adden zur Sei\u00adte tre\u00adten. Gemurrt wur\u00adde jedoch kaum.<\/p><p>Wir hat\u00adten ober\u00adhalb von Dra\u00adcken\u00addorf den Ein\u00adsied\u00adler\u00adberg umwan\u00addert, als die ers\u00adten Ultras auftauchten.<\/p><p><span class=\"dquo\">\u201c<\/span>L\u00e4u\u00adfer von rechts!\u201d, \u201cL\u00e4u\u00adfer von links!\u201d h\u00f6r\u00adte man sie schon von Wei\u00adtem. Sie hat\u00adten arg&nbsp;zu k\u00e4mp\u00adfen, um uns aus\u00adzu\u00adwei\u00adchen bzw. zum Bei\u00adsei\u00adte\u00adtre\u00adten zu bewe\u00adgen. Wir Wan\u00adde\u00adrer ver\u00admies\u00adten ihnen sicher den Lauf\u00adge\u00adnuss. Aber viel\u00adleicht war es auch ganz anders. Viel\u00adleicht sahen sie in uns so etwas wie huma\u00adne Hin\u00adder\u00adnis\u00adse, die der Sache einen zus\u00e4tz\u00adli\u00adchen Kick gaben. Wie\u00adso sonst, mal die \u00d6ff\u00adnungs\u00adzei\u00adten der Ver\u00adsor\u00adgungs\u00adstel\u00adlen aus\u00adge\u00adklam\u00admert, soll\u00adte man der Wan\u00adder\u00adge\u00admein\u00adde den Vor\u00adtritt las\u00adsen, um sie dann im Halb\u00addun\u00adkel ein\u00adzeln zu \u00fcber\u00adho\u00adlen? Wir waren \u00fcber 900 Leu\u00adte, die einer nach dem ande\u00adren berg\u00adauf und berg\u00adab durch die Gegend stie\u00adfel\u00adten. Ihr sport\u00adli\u00adcher Ehr\u00adgeiz wur\u00adde zudem nicht durch\u00adge\u00adhend mit Wohl\u00adwol\u00adlen auf\u00adge\u00adnom\u00admen. Sie nerv\u00adten. Es wur\u00adde gemurrt.<\/p><p>Iso\u00adt\u00adrink\u00adfix und Bana\u00adnen\u00adbei\u00ad\u00dfer hat\u00adte ich nicht unter den Vor\u00adbei\u00adl\u00e4u\u00adfern aus\u00adge\u00admacht, obschon sie es ver\u00adspro\u00adchen hat\u00adten. Und schon mach\u00adte ich mir Gedan\u00adken dar\u00ad\u00fcber, dass ich mir Gedan\u00adken \u00fcber sie machte.<\/p><p>Immer wie\u00adder pas\u00adsiert es mir, dass irgend\u00adwel\u00adche Men\u00adschen, die mich emo\u00adtio\u00adnal weni\u00adger ber\u00fch\u00adren als die besag\u00adte chi\u00adne\u00adsi\u00adsche Reist\u00fc\u00adte, mein Hirn beset\u00adzen. Wie die grau\u00adsig besch\u00e4\u00admen\u00adde Schnul\u00adze, die sich in unauf\u00admerk\u00adsa\u00admen Momen\u00adten im Ohr fest\u00addu\u00addelt und fort\u00adan den Tages\u00adrhyth\u00admus bestimmt, tau\u00adchen sie dann fort\u00adw\u00e4h\u00adrend unan\u00adge\u00admel\u00addet in mei\u00adnen Gedan\u00adken&nbsp;auf.<\/p><p>Zwei Unbe\u00adkann\u00adte von Wer-wei\u00df-woher<br>woll\u00adten schon immer ein wenig mehr<br>als all die ande\u00adren Unbe\u00adkann\u00adten,<br>die sich auf dem Marsch um Jena befanden.<\/p><p>Bedenk\u00adlich! \u00c4u\u00dferst bedenk\u00adlich! Sie setz\u00adten mir in Rei\u00admen zu und ich hat\u00adte noch gute 85 Kilo\u00adme\u00adter vor mir. Vor allem erwisch\u00adte ich mich dabei, wie ich ver\u00adsuch\u00adte, einen Sinn oder zumin\u00addest etwas Witz in die Ver\u00adse zu pres\u00adsen. Zudem ver\u00adz\u00fcck\u00adte mich der Gleich\u00adklang drei\u00ader Sta\u00adtio\u00adnen der ers\u00adten Etap\u00adpe. \u201eW\u00f6ll\u00adnitz, Ilm\u00adnitz, Z\u00f6ll\u00adnitz\u201c, dadai\u00adsier\u00adte ich vor mich&nbsp;her.<\/p><p>Ich fand jedoch kei\u00adnen Bezug zu bzw. zwi\u00adschen den Typen und Orten. Der Sinn\u00adstif\u00adter woll\u00adte mir par\u00adtout nicht erschei\u00adnen. Mein Hirn f\u00fchl\u00adte sich an, als w\u00e4re es ein wenig ange\u00adschwol\u00adlen. Druck\u00ademp\u00adfin\u00addun\u00adgen ober\u00adhalb mei\u00adner Aug\u00ad\u00e4p\u00adfel ver\u00adst\u00e4rk\u00adten die\u00adse Eingebung.<\/p><p><span class=\"dquo\">\u201e<\/span>O! O!\u201c&nbsp;Vor lau\u00adter Gr\u00fc\u00adbe\u00adlei hat\u00adte ich ver\u00adges\u00adsen, mei\u00adne Stirn\u00adlam\u00adpe aus\u00adzu\u00adpa\u00adcken.&nbsp;Nor\u00adma\u00adler\u00adwei\u00adse w\u00e4re das kein Pro\u00adblem gewe\u00adsen: Ruck\u00adsack ab, Stirn\u00adlam\u00adpe raus und auf\u00adge\u00adsetzt, Ruck\u00adsack auf, Stirn\u00adlam\u00adpe an und wei\u00adter. Aber Nor\u00adma\u00adler\u00adwei\u00adse war&nbsp;nicht.<\/p><p>Wir hat\u00adten bei Ilm\u00adnitz die Land\u00adstra\u00ad\u00dfe \u00fcber\u00adquert und einen absch\u00fcs\u00adsi\u00adgen Pfad erreicht. Er wur\u00adde rechts durch einen bewal\u00adde\u00adten Hang und links durch einen stei\u00adni\u00adgen Abgrund&nbsp;begrenzt und ma\u00df dazwi\u00adschen kei\u00adne drei\u00ad\u00dfig&nbsp;Zen\u00adti\u00adme\u00adter.&nbsp;Selbst bei Tages\u00adlicht und allein h\u00e4t\u00adte hier nie\u00admand gro\u00ad\u00dfe Spr\u00fcn\u00adge gemacht. Und jetzt war es dun\u00adkel, stock\u00addun\u00adkel. Ich hat\u00adte gar kei\u00adne Chan\u00adce ste\u00adhen zu blei\u00adben, um etwas aus\u00adzu\u00adpa\u00adcken. Alle Nach\u00adfol\u00adgen\u00adden h\u00e4t\u00adten war\u00adten m\u00fcs\u00adsen. Irgend\u00adei\u00adner h\u00e4t\u00adte bestimmt gescho\u00adben oder \u00e4hn\u00adli\u00adches und das h\u00e4t\u00adte wohl alle wie\u00adder in Bewe\u00adgung gesetzt und&nbsp;Bauz!<\/p><p>Also tip\u00adpel\u00adte ich mit dem Strom. Ich sah nicht immer, wo ich hin\u00adtrat. Ein\u00adzig die Lam\u00adpe mei\u00adnes Hin\u00adter\u00admanns zeig\u00adte mir etwas vom Weg. Zumeist stand ich mir dabei aber selbst im&nbsp;Licht.<\/p><p>Ich kam heil unten an. Dar\u00adauf gewet\u00adtet h\u00e4t\u00adte ich&nbsp;nicht.<\/p><p>Bis zur Ver\u00adsor\u00adgungs\u00adstel\u00adle Z\u00f6ll\u00adnitz war es dann nicht mehr all\u00adzu weit. Kurz vor halb elf erreich\u00adten wir den Fest\u00adplatz des Ortes. Hoch\u00adach\u00adtung vor den Hel\u00adfern. Der Ansturm der Wan\u00adder\u00admeu\u00adte ver\u00adlang\u00adte ihnen alles ab. Aber sie lie\u00ad\u00dfen sich nicht aus der Ruhe brin\u00adgen. Ihre Freund\u00adlich\u00adkeit war anste\u00adckend. Wir hat\u00adten uns etwas gest\u00e4rkt und zogen nach einer guten hal\u00adben Stun\u00adde weiter.<\/p><p>Zun\u00e4chst ging es nach Schie\u00adbel\u00adau. Wie der Esel hin\u00adter der M\u00f6h\u00adre lief ich dem Licht\u00adstrahl mei\u00adner Stirn\u00adlam\u00adpe hin\u00adter\u00adher. Au\u00dfer\u00adhalb des\u00adsen war alles schwarz. Die Welt war ausgeschaltet.<\/p><p>Vom Rit\u00adter\u00adguts\u00adhof selbst beka\u00admen wir nicht viel mit. Es war nach Mit\u00adter\u00adnacht. Ein\u00adzig die hei\u00admi\u00adschen Hun\u00adde sorg\u00adten f\u00fcr etwas Abwechs\u00adlung. Die Ein\u00adwoh\u00adner hat\u00adten eini\u00adges aus\u00adzu\u00adhal\u00adten. Denn nach uns kamen noch eini\u00adge Wan\u00adde\u00adrer, was die treu\u00aden Freun\u00adde der Men\u00adschen lan\u00adge nicht zur Ruhe kom\u00admen&nbsp;lie\u00df.<\/p><p>Weit nach der Geis\u00adter\u00adstun\u00adde<br>Bell\u00adten alle Hun\u00adde<br>Des Rit\u00adter\u00adguts\u00adhofs Schie\u00adbel\u00adau,<br>Denn all die unbe\u00adkann\u00adten<br>Hori\u00adzon\u00adta\u00adle\u00adque\u00adru\u00adlan\u00adten<br>Kreuz\u00adten \u2014 ganz genau -<br>Gera\u00adde Schiebelau.<\/p><p>Ich sch\u00fct\u00adtel\u00adte mich, als h\u00e4t\u00adte ich einen Molch ver\u00adschluckt. Es war nicht die ers\u00adte Lyrik\u00adpsy\u00adcho\u00adse, die mich heim\u00adsuch\u00adte. Doch \u00fcbli\u00adcher\u00adwei\u00adse gr\u00fcn\u00adde\u00adten die\u00adse auf eupho\u00adri\u00adschen Gr\u00fc\u00adbe\u00adlei\u00aden in bier\u00adtaum\u00adli\u00adger Atmo\u00adsph\u00e4\u00adre. Also einem v\u00f6l\u00adlig anders\u00adar\u00adti\u00adgen sozio-kul\u00adtu\u00adrel\u00adlen Background.<\/p><p>Nat\u00fcr\u00adlich gibt es Schlim\u00adme\u00adres, wie geschwol\u00adle\u00adne F\u00fc\u00dfe auf Wan\u00adder\u00adschaft zum Bei\u00adspiel. Ja, wenn man sich es aus\u00adsu\u00adchen k\u00f6nn\u00adte. War aber&nbsp;nicht!<\/p><p>Ich hat\u00adte bei\u00addes am Backen. Zudem mar\u00adschier\u00adten Tuti und Lars fern aller Abnut\u00adzungs\u00ader\u00adschei\u00adnun\u00adgen. Ich hat\u00adte M\u00fche, dran zu bleiben.<\/p><p>Mitt\u00adler\u00adwei\u00adle hat\u00adte sich das Feld der Wan\u00adders\u00adleu\u00adte weit aus\u00adein\u00adan\u00adder\u00adge\u00adzo\u00adgen. Den\u00adnoch hat\u00adten wir immer jeman\u00adden in Sicht\u00adwei\u00adte, der uns sozu\u00adsa\u00adgen f\u00fchr\u00adte. Auch sonst mein\u00adte es der Wan\u00adder\u00adgott sehr gut mit uns. Es war weder kalt noch \u00fcber\u00adm\u00e4\u00ad\u00dfig win\u00addig. Und es war tro\u00adcken. Luschenwetter!<\/p><p>Kurz hat\u00adten sich Iso\u00adt\u00adrink\u00adfix und Bana\u00adnen\u00adbei\u00ad\u00dfer durch mei\u00adne Gedan\u00adken gekalau\u00adert, aber es blieb nichts haf\u00adten. Daf\u00fcr hat\u00adte mich eine roman\u00adti\u00adsche Schrul\u00adle beseelt.<\/p><p>Zwi\u00adschen Maua und Leu\u00adtra stie\u00adgen wir eine Sen\u00adke hin\u00adab. Ich hat\u00adte mei\u00adne Stirn\u00adlam\u00adpe abge\u00adschal\u00adtet. Der Tun\u00adnel aus Dun\u00adkel\u00adheit um mich brach&nbsp;auf.<\/p><p>Die Umge\u00adbung offen\u00adbar\u00adte sich in grau\u00adblau\u00aden Sil\u00adhou\u00adet\u00adten und schwarztrie\u00adfen\u00adden Schat\u00adten. Von Nor\u00adden dr\u00e4ng\u00adte fah\u00adles Stadt\u00adlicht. Durch den Nacht\u00addunst blink\u00adten ver\u00adein\u00adzel\u00adte Ster\u00adne. Eine Eule zog dar\u00adun\u00adter jagd\u00adtrie\u00adbig ihre Kreise.<\/p><p>Wir waren einen Moment ste\u00adhen geblie\u00adben. Leich\u00adter k\u00fch\u00adler Wind weh\u00adte uns tal\u00adauf\u00adw\u00e4rts ent\u00adge\u00adgen, als w\u00fcr\u00adde die Nacht uns ihren Atem ins Gesicht hauchen.<\/p><p>Das muss das Gl\u00fcck sein, dach\u00adte ich. F\u00fcr einen Moment woll\u00adte ich mich unter eine Buche set\u00adzen und f\u00fcr immer blei\u00adben. Ich mal\u00adte mir aus, wie Wur\u00adzeln und \u00c4ste des Baums sich \u00fcber mei\u00adnen K\u00f6r\u00adper schlin\u00adgen und mich zuneh\u00admend in den Stamm pres\u00adsen w\u00fcr\u00adden. Bis zur Ver\u00adei\u00adni\u00adgung. Allein die Kon\u00adtu\u00adren mei\u00adnes Gesichts w\u00fcr\u00adden sich noch in der Rin\u00adde abzeich\u00adnen. Fort\u00adan w\u00fcr\u00adde ich den Vor\u00adbei\u00adkom\u00admen\u00adden, so sie sich im Schat\u00adten des Bau\u00admes aus\u00adru\u00adhen und besin\u00adnen w\u00fcr\u00adden, die Weis\u00adhei\u00adten des Kos\u00admos ein\u00adfl\u00fcs\u00adtern. Ich w\u00fcr\u00adde von Zufall und F\u00fcl\u00adle reden, von Sym\u00adbio\u00adse und Ener\u00adgie, bis sie \u00fcber\u00adzeugt w\u00e4ren, das Uni\u00adver\u00adsum habe sie ein\u00adge\u00adweiht und dazu aus\u00ader\u00adko\u00adren, es allen zu erz\u00e4hlen.<\/p><p>Das w\u00fcr\u00adde mir bestimmt Spa\u00df machen. War aber&nbsp;nicht!<\/p><p>Ober\u00adhalb des Hangs, den wir hin\u00adab kamen, wan\u00adder\u00adte eine Lich\u00adter\u00adket\u00adte Rich\u00adtung Westen.<\/p><p>Komisch, wit\u00adzel\u00adte ich in mich hin\u00adein, wie nah Gl\u00fcck und Gl\u00fcck doch bei\u00adein\u00adan\u00adder lie\u00adgen k\u00f6n\u00adnen.&nbsp;Wir hat\u00adten den Weg ver\u00adfehlt. Daf\u00fcr erleb\u00adte ich einen&nbsp;Nacht\u00adland\u00adschafts\u00adrausch, der sei\u00adne syn\u00adthe\u00adti\u00adschen und pflanz\u00adli\u00adchen Geschwis\u00adter in allen Belan\u00adgen in den Schat\u00adten stell\u00adte, und&nbsp;wir muss\u00adten nicht ein\u00admal umkeh\u00adren. In Leu\u00adtra, das eini\u00adge hun\u00addert Meter vor uns lag, w\u00fcr\u00adden wir wie\u00adder auf die vor\u00adge\u00adge\u00adbe\u00adne Stre\u00adcke geraten.<\/p><p>Der eine oder ande\u00adre h\u00e4t\u00adte hier\u00adbei viel\u00adleicht an \u00fcber\u00adir\u00addi\u00adschen Bei\u00adstand gedacht. Gl\u00fcck kann schon ver\u00adun\u00adsi\u00adchern. Aber was war schon pas\u00adsiert? Ein klei\u00adnes Miss\u00adge\u00adschick mit posi\u00adti\u00adver Wen\u00addung, eine \u00fcber\u00adra\u00adschen\u00adde Aus\u00adsch\u00fct\u00adtung von Dopa\u00admin, also nichts Uner\u00adkl\u00e4r\u00adli\u00adches, eine roman\u00adti\u00adsche Schrul\u00adle, mehr&nbsp;nicht.<\/p><p>Die Ver\u00adnunft hat\u00adte mich wie\u00adder. So wie die Gewiss\u00adheit, dass noch \u00fcber 65 Kilo\u00adme\u00adter vor uns lagen. Dazu gesell\u00adte sich sogleich die Ein\u00adsicht, dass ich in mei\u00adnem Leben noch nie 65 Kilo\u00adme\u00adter zusam\u00admen\u00adh\u00e4n\u00adgend gewan\u00addert war. Gewan\u00addert? Stimmungswechsel!<\/p><p>Gl\u00fccks\u00admo\u00admen\u00adte flie\u00adhen.<br>Sie waren nur gelie\u00adhen.<br>Was gab ich<br>eigent\u00adlich?<\/p><p>Gl\u00fccks\u00admo\u00admen\u00adte flie\u00adhen.<br>Sie wer\u00adden nie ver\u00adzie\u00adhen.<br>Ver\u00adgab ich<br>eigent\u00adlich?<\/p><p>Ich hab so viel ver\u00adspro\u00adchen.<br>Was hielt ich<br>\u00fcber\u00adhaupt?<\/p><p>Was hab ich mir ver\u00adspro\u00adchen<br>und nie an mich<br>geglaubt?<\/p><p>Wir hat\u00adten die <span class=\"caps\">A4<\/span> erreicht und trot\u00adte\u00adten west\u00adw\u00e4rts. Mei\u00adne&nbsp;Lyrik\u00adpsy\u00adcho\u00adse hat\u00adte sich eine depres\u00adsi\u00adve Ver\u00adstim\u00admung ein\u00adge\u00adfan\u00adgen. Die Auto\u00adbahn lie\u00adfer\u00adte den pas\u00adsen\u00adden Sound\u00adtrack.&nbsp;Es ging auf zwei Uhr mor\u00adgens zu, das hie\u00df wir waren bereits gute sie\u00adben Stun\u00adden unter\u00adwegs. Ich hat\u00adte in Gedan\u00adken die Ver\u00adse ver\u00adtont und brub\u00adbel\u00adte sie keh\u00adlig vor mich hin. Die Lauf\u00adst\u00f6\u00adcke hieb ich dazu im Takt in den Boden. Wal\u00adking&nbsp;blues.<\/p><p>Tuti und Lars beka\u00admen davon nichts mit. Lauf\u00adma\u00adschi\u00adnen. Bei\u00adde! Auch nicht gera\u00adde Bal\u00adsam f\u00fcr mei\u00adne See\u00adle. Ich walk\u00adte hinterher.<\/p><p>\u00dcber\u00adra\u00adschung! Lars hat\u00adte zwar davon gere\u00addet, doch irgend\u00adwie hat\u00adte ich es ver\u00adges\u00adsen. In der N\u00e4he von P\u00f6sen hat\u00adten sei\u00adne Freun\u00addin Melit\u00adta und sein Kum\u00adpel Mat\u00adti einen exklu\u00adsi\u00adven Ver\u00adsor\u00adgungs\u00adpos\u00adten ein\u00adge\u00adrich\u00adtet. Irgend\u00adwie hat\u00adte ich auch \u00fcber\u00adse\u00adhen, dass sich Juri, Mat\u00adtis Schwa\u00adger, unse\u00adrer klei\u00adnen Grup\u00adpe ange\u00adschlos\u00adsen&nbsp;hatte.<\/p><p>Die Ursa\u00adchen\u00adsu\u00adche schluck\u00adte ich mit dem ers\u00adten Bis\u00adsen her\u00adun\u00adter. Was f\u00fcr ein Gela\u00adge! Was f\u00fcr ein Kick! Neben beleg\u00adten Bro\u00adten gab es Kaf\u00adfee und Kuchen, Bier und Melo\u00adne. Wir schlemm\u00adten. Wir schwatz\u00adten. Wir mach\u00adten Wit\u00adze \u00fcber unse\u00adre m\u00fcden Kno\u00adchen und die paar Meter, die noch vor uns&nbsp;lagen.<\/p><p>Nach ca. zwan\u00adzig Minu\u00adten zogen wir wei\u00adter, satt und gl\u00fcck\u00adlich und gef\u00fchl\u00adte zehn Kilo leichter.<\/p><p>Melit\u00adta und Mat\u00adti beglei\u00adte\u00adten uns. Sie beteu\u00ader\u00adten mehr\u00adfach, dass kei\u00adne leis\u00adtungs\u00adf\u00f6r\u00addern\u00adden Sub\u00adstan\u00adzen in den Lecke\u00adrei\u00aden ver\u00adsteckt waren. Ich schenk\u00adte ihnen Glau\u00adben. Kein aber! Kein nen\u00adnens\u00adwer\u00adtes zumindest!<\/p><p>Bis zur Fest\u00adwie\u00adse Ammer\u00adbach, der n\u00e4chs\u00adten Ver\u00adsor\u00adgungs\u00adstel\u00adle, waren es noch knap\u00adpe 8 Kilo\u00adme\u00adter. Bestimmt h\u00e4t\u00adte ich es auch ohne das Men\u00adtaldo\u00adping geschafft, mei\u00adne psy\u00adchi\u00adsche Gesund\u00adheit h\u00e4t\u00adte dabei jedoch arg gelit\u00adten. Sicher nicht folgenlos.<\/p><p>Das Hoch\u00adge\u00adf\u00fchl war ein Hoch\u00adge\u00adf\u00fchl, also schon bald ver\u00adpufft. Die gef\u00fchl\u00adte Gewichts\u00adre\u00adduk\u00adti\u00adon glei\u00adcher\u00adma\u00ad\u00dfen. Unser klei\u00adnes Gefol\u00adge hat\u00adte sich ver\u00adein\u00adzelt. Ich trot\u00adte\u00adte wie\u00adder mal hinterher.<\/p><p>Die Mara\u00adthon\u00addi\u00adstanz ist f\u00fcr mich \u00fcbli\u00adcher\u00adwei\u00adse das Ma\u00df der Din\u00adge. Doch hier lang\u00adte es nicht ein\u00admal f\u00fcr die H\u00e4lf\u00adte. Nahe Cospoth begann ich wie\u00adder im Lauf\u00adstock\u00adtakt vor mich hin\u00adzu\u00adbrum\u00admen. Ich wuss\u00adte, dass ich noch ein\u00admal einen Mara\u00adthon lau\u00adfen muss\u00adte und dann noch ein\u00admal f\u00fcnf\u00adzehn Kilo\u00adme\u00adter. An mei\u00adnen Fu\u00df\u00adsoh\u00adlen wuch\u00adsen Bla\u00adsen. Ich hat\u00adte den&nbsp;Blues.<\/p><p>3:45 Uhr. Kilo\u00adme\u00adter 46. Fest\u00adwie\u00adse Ammer\u00adbach. Hin\u00adset\u00adzen, dach\u00adte ich, nur hin\u00adset\u00adzen. Aber nichts. Alle B\u00e4n\u00adke waren besetzt oder reser\u00adviert. Und das Gras war feucht. Ich mal\u00adte mir aus, wie ich mit feuch\u00adter Hose wei\u00adter\u00admar\u00adschie\u00adren w\u00fcr\u00adde und wie ich mir dabei den Wolf&nbsp;rieb.<\/p><p>An den Ver\u00adsor\u00adgungs\u00adst\u00e4n\u00adden herrsch\u00adte Gedr\u00e4n\u00adge. Anste\u00adhen! Wan\u00addern war schlimm, aber ste\u00adhen war der Hass. Sobald ich inne\u00adhielt, hat\u00adte ich den Ein\u00addruck, dass mich die Schwer\u00adkraft zu Boden dr\u00fcck\u00adte. Irgend\u00adwann hielt ich dann doch einen Ver\u00adsor\u00adgungs\u00adbeu\u00adtel und einen Kaf\u00adfee in den H\u00e4n\u00adden und als ich mei\u00adne Freun\u00adde fand, war mir die Gras\u00adfeuch\u00adte&nbsp;egal.<\/p><p>Ich l\u00fcm\u00admel\u00adte r\u00fcck\u00adlings, eine Plas\u00adtik\u00adt\u00fc\u00adte unterm Hin\u00adtern, auf der Wie\u00adse. Fu\u00df\u00adpfle\u00adge. Es sah nicht gut aus. An ver\u00adschie\u00adde\u00adnen Stel\u00adlen schien die Haut auf\u00adzu\u00adplat\u00adzen. Doch Tuti wuss\u00adte Rat. Er hat\u00adte ein Wun\u00adder\u00admit\u00adtel dabei, eine Art Wachs\u00adstift, der Bla\u00adsen mil\u00addern k\u00f6n\u00adne. Trotz mei\u00adner Skep\u00adsis behan\u00addel\u00adte ich die betrof\u00adfe\u00adnen Stel\u00adlen damit. Es k\u00fchl\u00adte. Tro\u00adcke\u00adne Str\u00fcmp\u00adfe w\u00e4ren auch nicht schlecht, dach\u00adte ich. War aber&nbsp;nicht!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1da98dc elementor-widget elementor-widget-image-gallery\" data-id=\"1da98dc\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"gallery-3\" class=\"gallery galleryid-149 gallery-columns-4 gallery-size-medium\"><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1da98dc\" data-elementor-lightbox-title=\"dsc02888\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjczLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4ODguanBnIiwic2xpZGVzaG93IjoiMWRhOThkYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02888.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02888-300x225.jpg\" class=\"attachment-medium size-medium\" alt srcset=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02888-300x225.jpg 300w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02888-768x576.jpg 768w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02888.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\"><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1da98dc\" data-elementor-lightbox-title=\"dsc02889\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjc0LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4ODkuanBnIiwic2xpZGVzaG93IjoiMWRhOThkYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02889.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02889-300x225.jpg\" class=\"attachment-medium size-medium\" alt srcset=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02889-300x225.jpg 300w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02889-768x576.jpg 768w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02889.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\"><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1da98dc\" data-elementor-lightbox-title=\"dsc02894\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjcxLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4OTQuanBnIiwic2xpZGVzaG93IjoiMWRhOThkYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02894.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02894-300x225.jpg\" class=\"attachment-medium size-medium\" alt srcset=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02894-300x225.jpg 300w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02894-768x576.jpg 768w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02894.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\"><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1da98dc\" data-elementor-lightbox-title=\"dsc02897\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjcyLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4OTcuanBnIiwic2xpZGVzaG93IjoiMWRhOThkYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02897.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02897-300x225.jpg\" class=\"attachment-medium size-medium\" alt srcset=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02897-300x225.jpg 300w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02897-768x576.jpg 768w, https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02897.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\"><\/a>\n\t\t\t<\/div><\/figure><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b328e5 elementor-widget elementor-widget-text-editor\" data-id=\"0b328e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Fort\u00adan jeder f\u00fcr sich. So war es abge\u00adspro\u00adchen. Wir ver\u00adlo\u00adren kein Wort dar\u00fcber.<\/p><p><span class=\"dquo\">\u201e<\/span>Leu\u00adte, ich geh schon mal los. Ihr habt mich eh gleich!\u201c<\/p><p>Ich dreh\u00adte mich auf die Sei\u00adte und dr\u00fcck\u00adte mich mit mei\u00adnen St\u00f6\u00adcken in die Senk\u00adrech\u00adte. Die Ruhe\u00adpau\u00adse war mir nicht all\u00adzu gut bekom\u00admen. Beim B\u00fccken nach mei\u00adnen Ruck\u00adsack sp\u00fcr\u00adte ich ein kr\u00e4f\u00adti\u00adges anhal\u00adten\u00addes Zie\u00adhen vom Brust\u00adbein \u00fcber die Schul\u00adter\u00adbl\u00e4t\u00adter in die Arme und zur\u00fcck den Schul\u00adter\u00adg\u00fcr\u00adtel ent\u00adlang, die Hals\u2011, Brust- und Len\u00adden\u00adwir\u00adbel hin\u00adab zum Kreuz\u00adbein. Von dort zog der Schmerz in die Bei\u00adne, wo er sich unbe\u00adfan\u00adgen ausbreitete.<\/p><p>Ich unter\u00addr\u00fcck\u00adte eine obs\u00adz\u00f6\u00adne Unmuts\u00adbe\u00adkun\u00addung und zog grum\u00admelnd ab. Ich woll\u00adte allein sein. Ich woll\u00adte fluchen.<\/p><p>Zun\u00e4chst ging es mal wie\u00adder berg\u00adauf. Hae\u00adckel\u00adstein. Mit der ein\u00adset\u00adzen\u00adden Mor\u00adgen\u00add\u00e4m\u00adme\u00adrung erhell\u00adte sich auch mei\u00adne Lau\u00adne. Ein wenig! Am Ernst-Hae\u00adckel-Denk\u00admal traf ich Tuti wie\u00adder. Wir genos\u00adsen f\u00fcr einen Moment die Aus\u00adsicht und trenn\u00adten uns end\u00adg\u00fcl\u00adtig. Ohne Thea\u00adtra\u00adlik. Wir waren schlie\u00df\u00adlich nicht auf einer Polar\u00adex\u00adpe\u00addi\u00adti\u00adon, son\u00addern wan\u00adder\u00adten auf einem Rund\u00adweg um Jena. Hier ging man nicht ver\u00adschol\u00adlen, h\u00f6chs\u00adtens kra\u00adchen und das war nichts Exis\u00adten\u00adti\u00adel\u00adles, wenn \u00fcber\u00adhaupt war es \u00e4rgerlich.<\/p><p>Kur\u00adze Zeit sp\u00e4\u00adter hat\u00adten mich auch Lars und Melit\u00adta sowie Juri und Mat\u00adti \u00fcber\u00adholt. Glei\u00adches Ritu\u00adal: Bis bald! Alles&nbsp;Gute!<\/p><p>Dann ging es wie\u00adder berg\u00adab und berg\u00adauf. Pauls\u00adberg. Kah\u00adles H\u00f6he. M\u00fcn\u00adchen\u00adro\u00addaer Grund. An einem Rast\u00adplatz, an dem ich vor\u00ad\u00fcber kam, hat\u00adte sich ein Wan\u00adde\u00adrer aus\u00adge\u00adstreckt. Ich war geneigt, mich dazu zu legen, konn\u00adte jedoch der Ein\u00adge\u00adbung wider\u00adste\u00adhen und st\u00f6\u00adckel\u00adte weiter.<\/p><p>Nur kurz dar\u00adauf traf ich auf Mat\u00adti. Er sprach mich sofort auf den ras\u00adten\u00adden Wan\u00adde\u00adrer an. Es war Juri! Ich hat\u00adte ihn nicht erkannt.<\/p><p>Juri woll\u00adte ein paar Minu\u00adten Ruhe. Sie br\u00e4uch\u00adten nicht zu war\u00adten, er k\u00e4me gleich nach.<\/p><p>Gleich zog sich dann in die L\u00e4n\u00adge. Es pas\u00adsiert schon mal, dass sich der eine oder ande\u00adre bei so einer Stre\u00adcke eine Aus\u00adzeit nimmt. Nicht immer fin\u00adden sie wie\u00adder in die Spur zur\u00fcck. Der Mann mit dem Ham\u00admer kann es auch subtil.<\/p><p>Wie es den bei\u00adden erging, ist eine ande\u00adre Geschich\u00adte. Mich mahn\u00adte die\u00adses Erleb\u00adnis jedoch zur Vor\u00adsicht. Immer wie\u00adder ist zu h\u00f6ren, dass Wan\u00adde\u00adrer am Ende eines lan\u00adgen Marschs beim Rast\u00adma\u00adchen ein\u00adschlie\u00adfen bzw. nicht mehr auf die Bei\u00adne kamen. Auch in den Hori\u00adzon\u00adta\u00adle-Foren wur\u00adde davor gewarnt. Doch wirk\u00adlich beun\u00adru\u00adhi\u00adgend emp\u00adfand ich es&nbsp;nicht.<\/p><p>Pl\u00f6tz\u00adlich ent\u00adsann ich mich, dass auch mir der Blitz\u00adschlaf schon man\u00adchen Streich gespielt hat\u00adte. Pein\u00adlich mit\u00adun\u00adter, wenn ich davon erz\u00e4h\u00adlen w\u00fcr\u00adde. Ergo? Zur\u00fcck zum&nbsp;Thema!<\/p><p>Kenn\u00adzei\u00adchen des Blitz\u00adschlafs ist sein \u00dcber\u00adra\u00adschungs\u00admo\u00adment. Klar ver\u00adsp\u00fcrt man eine gewis\u00adse M\u00fcdig\u00adkeit, aber Schlaf\u00adphan\u00adta\u00adsien kom\u00admen einem dabei genau so wenig in den Sinn, wie ero\u00adti\u00adsche Begier\u00adden beim Anblick unge\u00adwa\u00adsche\u00adner L\u00e4u\u00adfer\u00admau\u00adken. Doch dann <em>\u2013 <\/em>\u00dcber\u00adra\u00adschung<em> \u2013<\/em> ist man hell\u00adwach! Indes ist jedoch ein St\u00fcck der Lebens\u00adge\u00adschich\u00adte ver\u00adlo\u00adren gegangen.<\/p><p>Das ver\u00adwirrt und es dau\u00adert eine Wei\u00adle bis die Ori\u00aden\u00adtie\u00adrung wie\u00adder\u00adkehrt. Mit ihr kommt dann die Gewiss\u00adheit, dass da eini\u00adge Meter Film irrever\u00adsi\u00adbel ver\u00adschol\u00adlen sind, was wie\u00adder\u00adum reich\u00adlich Platz f\u00fcr Spe\u00adku\u00adla\u00adtio\u00adnen bie\u00adtet. Zeu\u00adgen hel\u00adfen manch\u00admal, die Erin\u00adne\u00adrungs\u00adl\u00fc\u00adcken zu schlie\u00ad\u00dfen. Mit ihren Erin\u00adne\u00adrun\u00adgen. Doch die sind extrem sympathieabh\u00e4ngig.<\/p><p>Ich schweif\u00adte ab. Die Angst vorm spon\u00adta\u00adnen Ein\u00adschla\u00adfen hat\u00adte ich ver\u00addr\u00e4ngt. Was nutz\u00adte es gro\u00df auf\u00adzu\u00adpas\u00adsen, wenn es ohne\u00adhin nichts half. Der Ham\u00admer\u00admann war kein Gr\u00fct\u00adze\u00adkopf, der jodelnd durchs Unter\u00adholz stampft. Ihn zu ent\u00adge\u00adhen, hie\u00df ihn zu igno\u00adrie\u00adren und Gl\u00fcck zu haben. Was er gar nicht ver\u00adknu\u00adsen kann, ist Froh\u00adsinn. Gut gelaun\u00adte L\u00e4u\u00adfer und Wan\u00adde\u00adrer mei\u00addet er wie Aus\u00ads\u00e4t\u00adzi\u00adge. Viel\u00adleicht lag es dar\u00adan, dass er mir die fol\u00adgen\u00adden Kilo\u00adme\u00adter nicht auf die Pel\u00adle r\u00fcckte.<\/p><p>Mein Kopf\u00adki\u00adno pr\u00e4\u00adsen\u00adtier\u00adte hoch\u00adnot\u00adpein\u00adli\u00adche Blitz\u00adschlaf\u00adge\u00adschich\u00adten aus eige\u00adner Pro\u00adduk\u00adti\u00adon. Umso besch\u00e4\u00admen\u00adder sie einst waren, des\u00adto ver\u00adgn\u00fcg\u00adli\u00adcher waren die Retrospektiven.<\/p><p>Kei\u00adnes\u00adwegs m\u00f6ch\u00adte ich die Tor\u00adtour von der <span class=\"caps\">B7<\/span> zum Land\u00adgra\u00adfen und wei\u00adter Rich\u00adtung Wind\u00adknol\u00adlen sch\u00f6n\u00adre\u00adden. Doch die klei\u00adnen auf\u00adge\u00adar\u00adbei\u00adte\u00adten Epi\u00adso\u00adden aus mei\u00adner Bio\u00adgra\u00adfie lenk\u00adten mich ein wenig ab. Den Fett\u00adn\u00e4p\u00adfen sei&nbsp;Dank!<\/p><p>Irgend\u00adwo zwi\u00adschen Rau\u00adtal und J\u00e4ger\u00adberg war es dann pas\u00adsiert. Die wei\u00df-rot-wei\u00ad\u00dfe Mar\u00adkie\u00adrung war ver\u00adschwun\u00adden. Der Weg, den ich ein\u00adge\u00adschla\u00adgen hat\u00adte, f\u00fchr\u00adte in ein Tal. Wie immer in der\u00adar\u00adti\u00adgen Situationen.<\/p><p>Umkeh\u00adren und den Hang wie\u00adder hin\u00adauf\u00adstie\u00adfeln, war nicht sehr ver\u00adlo\u00adckend. Immer\u00adhin bestand die M\u00f6g\u00adlich\u00adkeit, dass ich doch auf dem rich\u00adti\u00adgen Weg war. Und dann m\u00fcss\u00adte ich wie\u00adder umkeh\u00adren. Aber wei\u00adter&nbsp;gehen?<\/p><p>So weit ich bli\u00adcken konn\u00adte, scann\u00adte ich die B\u00e4u\u00adme nach Hori\u00adzon\u00adta\u00adle\u00adhin\u00adwei\u00adsen ab. Ich hoff\u00adte und bang\u00adte, aber nicht ein\u00admal eine Hal\u00adlu\u00adzi\u00adna\u00adti\u00adon woll\u00adte sich sehen las\u00adsen. Und ande\u00adre Wan\u00adde\u00adrer? Fehlanzeige!<\/p><p>Die Anzei\u00adchen, bes\u00adser die feh\u00adlen\u00adden Anzei\u00adchen, waren ein\u00addeu\u00adtig. Ich war falsch. Zur\u00fcck\u00adzu\u00adlau\u00adfen bis wie\u00adder eine Mar\u00adkie\u00adrung auf\u00adtaucht, w\u00e4re jetzt die ein\u00adzig rich\u00adti\u00adge Entscheidung.<\/p><p><span class=\"quo\">\u201a<\/span>Klug\u00adschei\u00ad\u00dfer!\u2019 moser\u00adte ich. Ich war zumin\u00addest ste\u00adhen geblie\u00adben. Und ste\u00adhen war der&nbsp;Hass.<\/p><p>Jeder Weg ein Schei\u00adde\u00adweg.<br>Jedes Mal die Qual der Wahl.<br>Doch ohne die\u00adses Pri\u00advi\u00adleg<br>W\u00e4re alles schei\u00df\u00adegal.<br>Jede Wahl der Mit\u00adtel\u00adweg,<br>Total nor\u00admal ist opti\u00admal.<br>Das Frem\u00adde ist ein Sakri\u00adleg,<br>Das Unbe\u00adkann\u00adte, schei\u00df\u00adegal!<br>Jeder sucht auf sei\u00adnem Weg<br>Ein\u00admal nur das gro\u00ad\u00dfe Los.<br>Das Schick\u00adsal sieht\u2019s nicht ein.<br>Jeder Weg ein Schei\u00adde\u00adweg.<br>Wir geh\u2019n nicht los,<br>Wir gehen&nbsp;ein!<\/p><p>Pes\u00adsi\u00admis\u00admus. Fata\u00adlis\u00adti\u00adscher Pes\u00adsi\u00admis\u00admus. Und auch noch mit Kraft\u00adaus\u00addr\u00fc\u00adcken deko\u00adriert. Mein psy\u00adchi\u00adsches Immun\u00adsys\u00adtem war sp\u00fcr\u00adbar an sei\u00adne Gren\u00adzen gera\u00adten. Hier ging es nicht mehr um eine tem\u00adpo\u00adr\u00e4\u00adre Lyrik\u00adpsy\u00adcho\u00adse. Die Sinn\u00adfra\u00adge beherrsch\u00adte mei\u00adnen Gedan\u00adken\u00adpa\u00adlast, die Sinn\u00adfra\u00adge in Per\u00adson des naiv-pene\u00adtran\u00adten Warum-Schei\u00dferchens.<\/p><p>Auf Blitz\u00adschlaf, Bla\u00adsen und Schul\u00adter\u00adkreuz\u00adh\u00fcft\u00adknie\u00adkn\u00f6\u00adchel\u00adschmer\u00adzen war ich mitt\u00adler\u00adwei\u00adle ganz gut ein\u00adge\u00adstellt. Igno\u00adrie\u00adren hilft wirk\u00adlich. Und ab und zu ein cou\u00adra\u00adgier\u00adter Fluch. Aber igno\u00adrie\u00adre mal den War\u00adum-Schei\u00ad\u00dfer oder ver\u00adflu\u00adche ihn&nbsp;gar!<\/p><p>Jam\u00admer. Er kon\u00adtert mit l\u00e4p\u00adpi\u00adschem, piep\u00adsi\u00adgem Jam\u00admer. Das willst du nicht&nbsp;h\u00f6ren!<\/p><p>War\u00adum gehst du nicht den beque\u00adme\u00adren Weg? War\u00adum musst du dich qu\u00e4\u00adlen? War\u00adum h\u00f6rst du nicht auf dei\u00adnen K\u00f6r\u00adper? War\u00adum reicht dir das bis\u00adher Geschaff\u00adte nicht? War\u00adum musst du es dir st\u00e4n\u00addig bewei\u00adsen? War\u00adum ist auf\u00adge\u00adben Luschen\u00adkram? War\u00adum sind dann Iso\u00adt\u00adrink\u00adfix und Bana\u00adnen\u00adbei\u00ad\u00dfer Arsch\u00adl\u00f6\u00adcher? War\u00adum hat Rot-Wei\u00df hier f\u00fcnf Buden kassiert?<\/p><p>Es gibt eine L\u00f6sung. Streich\u00adle das Ego des Schei\u00ad\u00dfers, bis er selbst\u00adver\u00adliebt ein\u00add\u00f6st! Gib ihm Recht! Spiel mit ihm! Und mach w\u00e4h\u00adrend\u00addes\u00adsen dein&nbsp;Ding!<\/p><p>Ich war den Berg wie\u00adder hin\u00adauf\u00adge\u00adkra\u00adxelt. F\u00fcnf\u00adzehn Minu\u00adten brauch\u00adte ich bis zur wei\u00df-rot-wei\u00ad\u00dfen Gewissheit.<\/p><p>Kaum war ich wie\u00adder auf dem rich\u00adti\u00adgen Weg, tauch\u00adten auch wie\u00adder Hori\u00adzon\u00adta\u00adlis\u00adten auf. Eini\u00adge wirk\u00adten arg mit\u00adge\u00adnom\u00admen. Nicht weni\u00adge hum\u00adpel\u00adten oder tip\u00adpel\u00adten. Bla\u00adsen. Zeh\u00adrun\u00adgen. Der Wolf. Ich \u00fcber\u00adhol\u00adte einen Wan\u00adder\u00adkol\u00adle\u00adgen, der einen m\u00e4ch\u00adti\u00adgen Ast als Kr\u00fc\u00adcke nutz\u00adte, und erkun\u00addig\u00adte mich, ob ich hel\u00adfen k\u00f6n\u00adne. Er schw\u00e4rm\u00adte vom Zieleinlauf.<\/p><p>Der War\u00adum-Schei\u00ad\u00dfer d\u00f6s\u00adte. Mei\u00adne F\u00fc\u00dfe waren geschwol\u00adlen. Vor wund gerie\u00adbe\u00adnen Stel\u00adlen und offe\u00adnen Bla\u00adsen blieb ich jedoch bis\u00adher ver\u00adschont. Tutis Wun\u00adder\u00admit\u00adtel sei geprie\u00adsen! Auch sonst waren die Beschwer\u00adden aus\u00adzu\u00adhal\u00adten, zeh\u00adrend, aber aus\u00adzu\u00adhal\u00adten. Ich dach\u00adte an die Wan\u00adder\u00adkol\u00adle\u00adgen. Ich hat\u00adte nichts auszuhalten!<\/p><p>Es war 9:00 Uhr durch. Die Wan\u00adde\u00adrerdich\u00adte hat\u00adte um eini\u00adges zuge\u00adnom\u00admen. Neben dem 100 Kilo\u00adme\u00adter-Gang gab es noch eine 35 Kilo\u00adme\u00adter-Sport\u00adwan\u00adde\u00adrung, die Sams\u00adtag\u00admor\u00adgen gegen 6:00 Uhr star\u00adte\u00adte. Es war ange\u00adnehm wie\u00adder mehr Men\u00adschen um sich zu haben. Mit Ver\u00adschie\u00adde\u00adnen wech\u00adsel\u00adte ich ein paar Wor\u00adte, all\u00adge\u00admei\u00adnes Hals- und Bein\u00adbruch, nichts Welt\u00adbe\u00adwe\u00adgen\u00addes, genau das, was ich jetzt brauchte.<\/p><p>Ich wei\u00df nicht mehr viel von der Nord\u00adpas\u00adsa\u00adge; weder die Land\u00adschaft um den Jagd\u00adberg noch der Orts\u00adteil Zw\u00e4t\u00adzen hat\u00adte mei\u00adnen Gedan\u00adken\u00adpa\u00adlast mit Bil\u00addern best\u00fcckt.<\/p><p>Ein\u00adzig an ein Orts\u00adschild von Kunitz kann ich mich erin\u00adnern. Es war von zwei Kilo\u00adme\u00adtern die Rede. In Kunitz war der drit\u00adte Ver\u00adsor\u00adgungs\u00adpunkt. Die Sieb\u00adzig w\u00fcr\u00adde fal\u00adlen. Obwohl ich mich kreuz\u00adlahm f\u00fchl\u00adte, kam ein wenig Eupho\u00adrie in mir auf. Zwei Drit\u00adtel der Stre\u00adcke hat\u00adte ich geschafft. Und dort k\u00f6nn\u00adte ich mich ein wenig aus\u00adru\u00adhen. Sit\u00adzen. F\u00fcnf Minu\u00adten sitzen.<\/p><p><span class=\"dquo\">\u201e<\/span>War\u00adum sind die letz\u00adten zwei Kilo\u00adme\u00adter nur immer so&nbsp;lang?\u201c<\/p><p>Gemach, gemach, Schei\u00ad\u00dfer\u00adchen! Das ist nur um dich zu tes\u00adten. Aber du bist ja auf der H\u00f6he der Auf\u00adga\u00adben. Leg dich ruhig wie\u00adder hin! Ich sag dir bescheid, wenn was ist. Ehrlich!<\/p><p>09:54 Uhr gab ich dem Stre\u00adcken\u00adpos\u00adten mei\u00adne Stech\u00adkar\u00adte. Rund um die Bus\u00adhal\u00adte\u00adstel\u00adle von Kunitz hat\u00adten die Ver\u00adan\u00adstal\u00adter eini\u00adges an Speis und Trank auf\u00adfah\u00adren las\u00adsen. Die Musik\u00adbox schep\u00adper\u00adte Pop\u00adtral\u00adla\u00adla. Fr\u00fch\u00adschop\u00adpen\u00adstim\u00admung. Die Ver\u00adsor\u00adger waren gro\u00dfartig.<\/p><p>Ich hat\u00adte mir einen Tel\u00adler mit Wurst\u00adstul\u00adlen und Kuchen sowie Kaf\u00adfee und Cola rei\u00adchen las\u00adsen und such\u00adte etwas hilf\u00adlos einen Platz. Selbst die Bord\u00adstein\u00adkan\u00adten waren besetzt. Eini\u00adge hat\u00adten sich r\u00fcck\u00adlings auf der Stra\u00ad\u00dfe aus\u00adge\u00adbrei\u00adtet. Bei Nah\u00adrungs\u00adauf\u00adnah\u00adme, Wund\u00adver\u00adsor\u00adgung und Erho\u00adlungs\u00adri\u00adtua\u00adlen wur\u00adden zeit\u00adge\u00adm\u00e4\u00ad\u00dfe kul\u00adtu\u00adrel\u00adle Nor\u00admen nicht all\u00adzu eng gese\u00adhen. Auch mei\u00adne Kin\u00adder\u00adstu\u00adbe hat\u00adte gelit\u00adten. Ich hat\u00adte einen Platz-da-Br\u00fcl\u00adler ange\u00adstaut, der kurz vor der Erup\u00adti\u00adon&nbsp;stand.<\/p><p>Auf ein\u00admal stand Lars vor mir. Ich press\u00adte ein klein\u00adlau\u00adtes Hal\u00adlo her\u00adaus, mehr war nicht drin. Lars grins\u00adte und schob mich hin\u00adters War\u00adte\u00adh\u00e4us\u00adchen. Dort hat\u00adte er zwei Meter Bord\u00adstein besetzt. Genug Platz f\u00fcr uns drei. Melit\u00adta hat\u00adte, w\u00e4h\u00adrend er mich ansprach, die Stel\u00adlung gehalten.<\/p><p>Sit\u00adzen. Oder so. Und Essen. Und Kaf\u00adfee schl\u00fcr\u00adfen. Und Freun\u00adde. Herz, was willst du&nbsp;mehr?<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c54e3c elementor-widget elementor-widget-image-gallery\" data-id=\"9c54e3c\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"gallery-4\" class=\"gallery galleryid-149 gallery-columns-6 gallery-size-thumbnail\"><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02899\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgyLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI4OTkuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02899.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02899-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02900\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgzLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MDAuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02900.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02900-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02902\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg0LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MDIuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02902.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02902-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02903\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg1LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MDMuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02903.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02903-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02904\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjc1LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MDQuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02904.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02904-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02907\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjc2LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MDcuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02907.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02907-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02909\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjc3LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MDkuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02909.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02909-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02910\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjc4LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MTAuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02910.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02910-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02911\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjc5LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MTEuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02911.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02911-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02913\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MTMuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02913.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02913-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9c54e3c\" data-elementor-lightbox-title=\"dsc02914\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgxLCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvZHNjMDI5MTQuanBnIiwic2xpZGVzaG93IjoiOWM1NGUzYyJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02914.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/dsc02914-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d6219bc elementor-widget elementor-widget-text-editor\" data-id=\"5d6219bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Lars und ich hat\u00adten ver\u00adein\u00adbart, die letz\u00adten Drei\u00ad\u00dfig gemein\u00adsam anzu\u00adge\u00adhen bzw. durch\u00adzu\u00adste\u00adhen. Melit\u00adta hat\u00adte indes den R\u00fcck\u00adzug ange\u00adtre\u00adten. Sie woll\u00adte von vorn\u00adher\u00adein nur eine Etap\u00adpe mit\u00adlau\u00adfen. Letzt\u00adend\u00adlich hat\u00adte es ihr wohl auch gereicht. Ich dach\u00adte noch mal an das Nacht\u00adbuf\u00adfet an der Auto\u00adbahn. Was f\u00fcr ein Sup\u00adport!&nbsp;Irre!<\/p><p>Kunitz\u00adburg hie\u00df das n\u00e4chs\u00adte Zwi\u00adschen\u00adziel. Also berg\u00adauf. Ich hat\u00adte mal wie\u00adder Anlauf\u00adpro\u00adble\u00adme, ver\u00adkniff mir jedoch jeg\u00adli\u00adche \u00c4u\u00dfe\u00adrung. Ange\u00adsicht der Schrun\u00adden die Lars sich zuzog, war das Luschengejammer.<\/p><p>Lars hat\u00adte sich bei sei\u00adner Aus\u00adr\u00fcs\u00adtung etwas ver\u00adtan. So mar\u00adschier\u00adte er mit Arbeits\u00adschu\u00adhen. Die\u00adse hat\u00adten ihm bei einer alpi\u00adnen Wan\u00adde\u00adrung gute Diens\u00adte geleis\u00adtet. Stre\u00adcken\u00adl\u00e4n\u00adge und \u2011pro\u00adfil der Hori\u00adzon\u00adta\u00adle waren sie weni\u00adger gewach\u00adsen. Die Soh\u00adlen l\u00f6s\u00adten sich lang\u00adsam auf. Zudem mal\u00adtr\u00e4\u00adtier\u00adten die Stahl\u00adkap\u00adpen sei\u00adne Zehen. Auf Wan\u00adder\u00adst\u00f6\u00adcke hat\u00adte er au\u00dfer\u00addem ver\u00adzich\u00adtet. Das r\u00e4ch\u00adte sich nun zunehmend.<\/p><p>Mitt\u00adler\u00adwei\u00adle war es zw\u00f6lf Uhr durch. Es war warm, aber nicht all\u00adzu hei\u00df. Gef\u00fchl\u00adte 24 Grad. Die Son\u00adne war bes\u00adtens hin\u00adter dich\u00adten Hau\u00adfen\u00adwol\u00adken versteckt.<\/p><p>Wir hat\u00adten auf dem Huf\u00adei\u00adsen, einem bewal\u00adde\u00adten H\u00f6hen\u00adzug, Las\u00ada\u00adan umwan\u00addert und qu\u00e4l\u00adten uns ins Tal nach Wogau. Der Berg\u00adweg hat\u00adte es in sich. Meh\u00adre\u00adre Anstie\u00adge reih\u00adten sich anein\u00adan\u00adder. Aber das steck\u00adte ich eini\u00adger\u00adma\u00ad\u00dfen weg. An mei\u00adne Gren\u00adzen geriet ich jedoch bei den Abstie\u00adgen. Beson\u00adders das Hin\u00adab am s\u00fcd\u00adwest\u00adli\u00adchen Ende des Huf\u00adei\u00adsens weck\u00adte den War\u00adum-Schei\u00ad\u00dfer in mir. Cir\u00adka zwei Kilo\u00adme\u00adter scharf\u00adstei\u00adni\u00adger Unter\u00adgrund bei cir\u00adka 50 Pro\u00adzent Gef\u00e4lle.<\/p><p>Bei jedem Schritt wur\u00adden s\u00e4mt\u00adli\u00adche Gelen\u00adke durch ein Viel\u00adfa\u00adches mei\u00adnes K\u00f6r\u00adper\u00adge\u00adwichts inein\u00adan\u00adder\u00adge\u00adpresst. Die F\u00fc\u00dfe quetsch\u00adten sich in den vor\u00adde\u00adren Teil mei\u00adner Wan\u00adder\u00adschu\u00adhe. Die Zehen waren ein\u00adge\u00adrollt und geschwol\u00adlen. Dank mei\u00adner Wan\u00adder\u00adst\u00f6\u00adcke konn\u00adte ich die Wucht beim Auf\u00adtre\u00adten ein wenig abfe\u00addern. Lars hat\u00adte kei\u00adne Wan\u00adder\u00adst\u00f6\u00adcke. Lars trug abge\u00adlau\u00adfe\u00adne Arbeitsschuhe.<\/p><p>Ich hat\u00adte davon geh\u00f6rt, dass bei l\u00e4n\u00adge\u00adren Stre\u00adcken und dem\u00adentspre\u00adchen\u00adden Beschwer\u00adden, Wan\u00adde\u00adrer Teil\u00adst\u00fc\u00adcke r\u00fcck\u00adw\u00e4rts lau\u00adfen. Lars lief seit\u00adw\u00e4rts. So konn\u00adte er es ver\u00admei\u00adden, dass jedes Mal, wenn er beim Abstieg auf\u00adtrat, die Stahl\u00adkap\u00adpen sei\u00adner Arbeits\u00adschu\u00adhe in sei\u00adne Zehen schnit\u00adten. Lars nahm es klag\u00adlos hin. Sein Lauf\u00adstil und sei\u00adne Mimik ver\u00adrie\u00adten jedoch, dass er&nbsp;litt.<\/p><p>In Wogau und Jena\u00adprie\u00df\u00adnitz ging es arg wei\u00adter. Kopf\u00adstein\u00adpflas\u00adter. Asphalt. Selbstironie.<\/p><p>Zuneh\u00admend nah\u00admen wir unse\u00adre Nai\u00advi\u00adt\u00e4t aufs Korn. Ich erin\u00adner\u00adte mich, wie ich am 28. Febru\u00adar kurz nach Mit\u00adter\u00adnacht zum Anmel\u00adde\u00adstart eine fr\u00f6h\u00adli\u00adche Bier\u00adrun\u00adde abrupt ver\u00adlie\u00df und heim rann\u00adte, weil ich mich nicht mit dem Han\u00addy auf der Hori\u00adzon\u00adta\u00adle-Sei\u00adte ein\u00adlog\u00adgen konn\u00adte. Ich bef\u00fcrch\u00adte\u00adte, die Start\u00adpl\u00e4t\u00adze w\u00fcr\u00adden post\u00adwen\u00addend aus\u00adge\u00adbucht sein. Nach mei\u00adner R\u00fcck\u00adkehr waren die Kum\u00adpels ver\u00adschwun\u00adden. Das hing mir lan\u00adge nach. Auch weil das Teil\u00adneh\u00admer\u00adli\u00admit von 1.000 Star\u00adtern nie erreicht wor\u00adden&nbsp;war.<\/p><p>Selbst\u00adiro\u00adnie half ein wenig. Obwohl ich geste\u00adhen muss, dass der War\u00adum-Schei\u00ad\u00dfer dabei unbe\u00adhel\u00adligt mitjaulte.<\/p><p>Hin\u00adter Jena\u00adprie\u00df\u00adnitz hat\u00adte die hei\u00admi\u00adsche Reser\u00adve\u00adar\u00admee eine klei\u00adne Zusatz\u00adver\u00adk\u00f6s\u00adti\u00adgungs\u00adstel\u00adle ein\u00adge\u00adrich\u00adtet. Kaf\u00adfee. Obst. Trau\u00adben\u00adzu\u00adcker. Und Sitzm\u00f6glichkeiten.<\/p><p>Vie\u00adle der anwe\u00adsen\u00adden Hori\u00adzon\u00adta\u00adlis\u00adten waren mir inzwi\u00adschen zumin\u00addest vom Sehen her bekannt. Mehr\u00adfach hat\u00adten wir uns gegen\u00adsei\u00adtig \u00fcber\u00adholt und dabei einen auf\u00admun\u00adtern\u00adden Gru\u00df zuge\u00adru\u00adfen. Nun sa\u00dfen Lars und ich vorm Jena\u00adprie\u00df\u00adnit\u00adzer Reser\u00advis\u00adten\u00adstand inmit\u00adten der Wan\u00adder\u00adge\u00admein\u00adde auf Bier\u00adb\u00e4n\u00adken und spann\u00adten Hori\u00adzon\u00adta\u00adleg\u00adarn. Alles erleb\u00adte Leid war auf ein\u00admal Anlass f\u00fcr Wit\u00adze und Sp\u00f6t\u00adte\u00adlei\u00aden. Wir lach\u00adten. Die Stim\u00admung war aus\u00adge\u00adlas\u00adsen. Mit Ver\u00adbis\u00adsen\u00adheits\u00adein\u00adla\u00adge\u00adrun\u00adgen. Im posi\u00adti\u00adven&nbsp;Sinn.<\/p><p>Dann ging es west\u00adw\u00e4rts. Fel\u00adder und Wald und berg\u00adan. Nach gut einer Stun\u00adde hat\u00adten wir den Haus\u00adberg erreicht und trepp\u00adauf den Anstieg zum Fuchs\u00adturm bew\u00e4ltigt.<\/p><p>Der Fuchs\u00adturm war einst Haupt\u00adturm der Burg Kirch\u00adberg. Heu\u00adte wird das 30 Meter hohe Gem\u00e4u\u00ader als Aus\u00adsichts\u00adturm genutzt. In der Burg\u00adan\u00adla\u00adge wur\u00adde nat\u00fcr\u00adlich eine Aus\u00adflugs\u00adgast\u00adst\u00e4t\u00adte ein\u00adge\u00adrich\u00adtet. Wie es uns gelang, die Schank\u00adwirt\u00adschaft zu igno\u00adrie\u00adren, kann ich nicht mehr genau sagen. Ver\u00admut\u00adlich war sie geschlossen.<\/p><p>Statt Bier genos\u00adsen wir einen Moment lang den Rund\u00adblick \u00fcber das Jena\u00ader Land. Ich hat\u00adte ver\u00adsucht unse\u00adren Weg am Hori\u00adzont nach\u00adzu\u00adver\u00adfol\u00adgen. Das Aus\u00adma\u00df der Stre\u00adcke erschien mir jedoch unwirk\u00adlich. Auch das Erleb\u00adte wirk\u00adte pl\u00f6tz\u00adlich nicht mehr real, eher wie Epi\u00adso\u00adden eines Films. Nichts bleibt!<\/p><p>Das war das Signal zum Auf\u00adbruch. Mein Hirn woll\u00adte gera\u00adde den Sinn\u00adlos\u00admo\u00addus hoch\u00adfah\u00adren, doch ich war schon auf den Bei\u00adnen. Zuneh\u00admend bekam ich mei\u00adne Gr\u00fc\u00adbel\u00adgeis\u00adter in den Griff. Das wohl auch, weil sich unwei\u00adger\u00adlich das ver\u00adtrau\u00adte Ersch\u00f6p\u00adfungs- und Schmerz\u00adle\u00advel ein\u00adstell\u00adte. Von wegen nichts bleibt.<\/p><p>Wir hat\u00adten Gl\u00fcck, ein auf\u00admerk\u00adsa\u00admer Wan\u00adder\u00adkol\u00adle\u00adge hat\u00adte uns recht\u00adzei\u00adtig kor\u00adri\u00adgiert. Die 35-km- und 100-km-Stre\u00adcke ver\u00adlie\u00adfen fort\u00adan auf ver\u00adschie\u00adde\u00adnen Pfa\u00adden. Ande\u00adre hat\u00adten weni\u00adger Mas\u00adsel, eini\u00adge 35-km-Akti\u00advis\u00adten kamen uns auf der Stra\u00ad\u00dfe zum Stein\u00adkreuz ent\u00adge\u00adgen und nicht alle waren froh gestimmt.<\/p><p>14:19 Uhr. Stein\u00adkreuz. Wir waren jetzt \u00fcber 20 Stun\u00adden am Start. Wir hat\u00adten 85 km abge\u00adris\u00adsen. Wir waren gut drauf; v\u00f6l\u00adlig platt, aber gut&nbsp;drauf.<\/p><p>Es ist unred\u00adlich die Ver\u00adsor\u00adgungs\u00adstel\u00adlen zu ver\u00adglei\u00adchen, alle hat\u00adten sie Gro\u00df\u00adar\u00adti\u00adges geleis\u00adtet. Aber am Stein\u00adkreuz hat\u00adte ich das Gef\u00fchl in der VIP-Lounge der Hori\u00adzon\u00adta\u00adle zu lan\u00adden. Wir wur\u00adden von den Ehren\u00adamt\u00adli\u00adchen aufs Freund\u00adlichs\u00adte begr\u00fc\u00dft. Die Ver\u00adpfle\u00adgung war vom Feins\u00adten. Und dabei waren die Hel\u00adfer hier schon seit 7:00 Uhr im Ein\u00adsatz ohne Vor\u00adbe\u00adrei\u00adtungs- und Anfahrtszeit.<\/p><p>Die anwe\u00adsen\u00adden Mar\u00adschie\u00adrer, viel\u00adleicht f\u00fcnf\u00adzehn Leu\u00adte, hat\u00adten alle an einer gro\u00ad\u00dfen Bier\u00adgar\u00adni\u00adtur Platz gefun\u00adden. Es herrsch\u00adte ein Stim\u00admung wie beim Motivationsseminar.<\/p><p>An mei\u00adner Sei\u00adte hat\u00adte ein jun\u00adger Mann sei\u00adne F\u00fc\u00dfe frei\u00adge\u00adlegt, um sei\u00adne auf\u00adge\u00adplatz\u00adten blu\u00adten\u00adden Bla\u00adsen zu ver\u00adarz\u00adten. Er erz\u00e4hl\u00adte mir dabei Hori\u00adzon\u00adta\u00adle\u00adge\u00adschich\u00adten ver\u00adgan\u00adge\u00adner Tage. Hin und wie\u00adder zeig\u00adte er Anzei\u00adchen von Schmer\u00adzen, die er aber sofort iro\u00adnisch kom\u00admen\u00adtier\u00adte. Dann sprach er von den letz\u00adten hun\u00addert Metern bis zum Ziel. Mit dem L\u00e4cheln h\u00e4t\u00adte er jede Pr\u00e4\u00adsi\u00addent\u00adschafts\u00adwahl in den Ver\u00adei\u00adnig\u00adten Staa\u00adten gewonnen.<\/p><p>Pl\u00f6tz\u00adlich mel\u00adde\u00adte sich Lars. Tuti hat\u00adte ein Bild gesen\u00addet. Es zeig\u00adte ihn, wie er im Kof\u00adfer\u00adraum eines Octa\u00advia Scouts sitzt und ein Fu\u00df\u00adbad geniest.<\/p><p>Er war also im Ziel. Unglaub\u00adlich, er hat\u00adte gegen\u00ad\u00fcber Lars und mir f\u00fcnf\u00adzehn Kilo\u00adme\u00adter raus\u00adge\u00adwan\u00addert. Ab Kilo\u00adme\u00adter f\u00fcnfzig!<\/p><p>Einer von uns Drei\u00aden hat\u00adte es also geschafft und wird nun war\u00adten und uns die Dau\u00admen dr\u00fc\u00adcken. Er wuss\u00adte, was uns noch bevorstand.<\/p><p>Inzwi\u00adschen mach\u00adte die Nach\u00adricht die Run\u00adde, dass eine Hori\u00adzon\u00adta\u00adle-Akti\u00advis\u00adtin abbre\u00adchen w\u00fcr\u00adde. F\u00fcnf\u00adzehn Kilo\u00adme\u00adter vorm Ziel. Eine Ent\u00adfer\u00adnung, die ange\u00adsichts der Hun\u00addert fast l\u00e4cher\u00adlich wirk\u00adte. So rich\u00adtig ver\u00adste\u00adhen konn\u00adte ich es erst nicht. Aber ich hat\u00adte auch nichts wei\u00adter aus\u00adzu\u00adste\u00adhen. Ich wei\u00df nicht, wie ich reagie\u00adren w\u00fcr\u00adde, wenn es mir wie mei\u00adnem Nach\u00adbarn oder Lars erge\u00adhen w\u00fcr\u00adde. Immer\u00adhin hat\u00adten wir noch fast vier Stun\u00adden Lauf\u00adzeit vor uns und das Stre\u00adcken\u00adpro\u00adfil lie\u00df eini\u00adges bef\u00fcrchten.<\/p><p>Wan\u00adder\u00adlust und Natur\u00ader\u00adleb\u00adnis\u00adse zogen nicht mehr. Es war wohl Ehr\u00adgeiz und Arro\u00adganz, die mich wei\u00adter trie\u00adben. Ich woll\u00adte nicht zur\u00fcck\u00adste\u00adhen. Auf\u00adge\u00adben ist Luschen\u00adkram! Iso\u00adt\u00adrink\u00adfix und Bana\u00adnen\u00adbei\u00ad\u00dfer sa\u00dfen wie Wal\u00addorf und Stat\u00adler auf der Empo\u00adre mei\u00adnes Gedan\u00adken\u00adpa\u00adlas\u00adtes und feix\u00adten sich&nbsp;eins.<\/p><p>Sogleich hat\u00adte sich auch das War\u00adum-Schei\u00ad\u00dfer\u00adchen in mir gemel\u00addet. War\u00adum l\u00e4sst du es nicht auch gut sein? War\u00adum nimmst du dir nicht an die\u00adser aut\u00adar\u00adken Per\u00ads\u00f6n\u00adlich\u00adkeit ein Beispiel?<\/p><p>Und dann tricks\u00adte ich mich aus. Ich sag\u00adte Lars, dass ich wei\u00adter m\u00f6ch\u00adte. Er nick\u00adte und wir stampf\u00adten los. Ich woll\u00adte so schnell wie m\u00f6g\u00adlich Zie\u00adgen\u00adhain hin\u00adter mir las\u00adsen und die Kern\u00adber\u00adge hinauf.<\/p><p>Irgend\u00adwie gelang es mir, mei\u00adne Lau\u00adnen und Zwei\u00adfel auf Abstand zu hal\u00adten. Ich wuss\u00adte, es war nur eine Fra\u00adge der Zeit und sie w\u00fcr\u00adden wie\u00adder \u00fcber mich her\u00adfal\u00adlen. Doch dann w\u00e4re es zu sp\u00e4t zum Auf\u00adge\u00adben. In den Kern\u00adber\u00adgen h\u00e4t\u00adte mich kei\u00adner abho\u00adlen k\u00f6n\u00adnen. Ins Ziel zu mar\u00adschie\u00adren, w\u00e4re dann die ein\u00adzig sinn\u00advol\u00adle Option.<\/p><p>Die Abbre\u00adcher\u00adquo\u00adte bei dem 100-Kilo\u00adme\u00adter-Gang ist rela\u00adtiv hoch. Scha\u00adde, dass sie kaum Erw\u00e4h\u00adnung fin\u00adden. Sie h\u00e4t\u00adten alle eine Hori\u00adzon\u00adta\u00adle-Nadel ver\u00addient. Ihrer Selbst\u00adbe\u00adherr\u00adschung ver\u00addan\u00adken schlie\u00df\u00adlich alle, die ins Ziel kom\u00admen, dass sie unge\u00adzwun\u00adge\u00adne fei\u00adern k\u00f6n\u00adnen. Nicht aus\u00adzu\u00adden\u00adken, wenn sie bis zum Umfal\u00adlen wei\u00adter\u00admar\u00adschie\u00adren w\u00fcr\u00adden. Letzt\u00adend\u00adlich w\u00e4re die\u00adse Ver\u00adan\u00adstal\u00adtung unter die\u00adsen Umst\u00e4n\u00adden nicht m\u00f6g\u00adlich. Nie\u00admand w\u00fcr\u00adde das ver\u00adant\u00adwor\u00adten wol\u00adlen oder k\u00f6nnen.<\/p><p>Ich ken\u00adne die jun\u00adge Frau nicht, aber ich zie\u00adhe den Hut, wie auch vor all den ande\u00adren, die sich f\u00fcr ihr eige\u00adnes Tages\u00adziel ent\u00adschie\u00adden haben bzw. ent\u00adschei\u00adden wer\u00adden. Sich ein\u00adge\u00adste\u00adhen k\u00f6n\u00adnen, dass es nicht mehr wei\u00adter geht, hei\u00dft doch, dass man bis an sei\u00adne Gren\u00adzen gegan\u00adgen ist und dies akzep\u00adtie\u00adren&nbsp;kann.<\/p><p>Wir hat\u00adten die Kern\u00adber\u00adge erreicht und den letz\u00adten gr\u00f6\u00ad\u00dfe\u00adren Anstieg bew\u00e4l\u00adtigt. In luf\u00adti\u00adger H\u00f6he ging es auf einem schma\u00adlen stei\u00adni\u00adgen Weg wei\u00adter. Am Him\u00admel hat\u00adte sich eini\u00adges zusam\u00admen\u00adge\u00adballt. Doch der USV-Sport\u00adplatz war schon zu sehen. Zun\u00e4chst zumin\u00addest. Nach einem Links\u00adschwenk ver\u00adlo\u00adren wir das gro\u00ad\u00dfe Ziel wie\u00adder aus den Augen. Daf\u00fcr blies der Wind pl\u00f6tz\u00adlich kr\u00e4f\u00adti\u00adger. Ein gro\u00ad\u00dfer Regen\u00adtrop\u00adfen klatsch\u00adte mir ins Gesicht.<\/p><p>15:30 Uhr. Wol\u00adken\u00adbruch. Wir hat\u00adten ent\u00adschie\u00adden wei\u00adter\u00adzu\u00admar\u00adschie\u00adren. Es war nicht abzu\u00adse\u00adhen, wie lan\u00adge das Gewit\u00adter gehen w\u00fcr\u00adde. Das Ziel dage\u00adgen war abzu\u00adse\u00adhen. Und irgend\u00adwann dem\u00adn\u00e4chst m\u00fcss\u00adte ja der Weg hin\u00adab f\u00fch\u00adren. Letztmalig.<\/p><p>Wir muss\u00adten wie\u00adder hin\u00adter ein\u00adan\u00adder lau\u00adfen. Zwi\u00adschen den stei\u00adlen Muschel\u00adkalk\u00adfel\u00adsen lin\u00adker\u00adhand und den glei\u00adcher\u00adma\u00ad\u00dfen stei\u00adlen Abh\u00e4n\u00adgen auf der rech\u00adten Sei\u00adte blieb nicht all\u00adzu viel Platz. Zudem hat\u00adten sich Rinn\u00adsa\u00adle oder bes\u00adser klei\u00adne Sturz\u00adb\u00e4\u00adche auf dem Pfad gebil\u00addet, die uns ent\u00adge\u00adgen\u00adstr\u00f6m\u00adten. Es war nicht unge\u00adf\u00e4hr\u00adlich. Gera\u00adde in den Bie\u00adgun\u00adgen war der Boden absch\u00fcs\u00adsig und glatt. Trotz\u00addem lie\u00adfen wir schneller.<\/p><p>Ange\u00adsichts des nahen\u00adden Ziels und des Unwet\u00adters konn\u00adte ich noch irgend\u00adwo\u00adher Ener\u00adgie frei\u00adset\u00adzen, was wahr\u00adschein\u00adlich dazu f\u00fchr\u00adte, dass eini\u00adge Hirn\u00adarea\u00adle unter\u00adver\u00adsorgt blie\u00adben. Den Kon\u00adtakt mit der Au\u00dfen\u00adwelt hat\u00adte ich abge\u00adbro\u00adchen. Ich fluch\u00adte. Ich jam\u00admer\u00adte. Und fleh\u00adte den ver\u00addamm\u00adten Abstieg her\u00adbei. Regen und Wind blie\u00adben unbeeindruckt.<\/p><p>Dann ging es berg\u00adab. Noch bevor wir den F\u00fcrs\u00adten\u00adbrun\u00adnen erreich\u00adten, war das Unwet\u00adter vor\u00adbei. Mein Denk\u00adap\u00adpa\u00adrat schal\u00adte\u00adte sofort auf Ziel\u00adein\u00adlauf. Vier Kilo\u00adme\u00adter. Das war\u2019s dann. Auch das Gewit\u00adter wer\u00adte\u00adte ich umge\u00adhend um. So kurz vor Schluss gab es doch der Wan\u00adde\u00adrung noch eine zus\u00e4tz\u00adli\u00adche aben\u00adteu\u00ader\u00adli\u00adche&nbsp;Note.<\/p><p>Die Gro\u00df\u00adkotz\u00adlau\u00adne leg\u00adte sich als\u00adbald. Die vier Kilo\u00adme\u00adter woll\u00adten nicht vor der Zeit abdan\u00adken. Eine Stun\u00adde war noch. Mindestens.<\/p><p>Der Weg durchs Peni\u00adcken\u00adtal erwies sich noch eini\u00adger\u00adma\u00ad\u00dfen ertr\u00e4g\u00adlich. Ab W\u00f6ll\u00adnitz hat\u00adten wir dann wie\u00adder Asphalt unter unse\u00adren durch\u00adn\u00e4ss\u00adten Schu\u00adhen. Lars steck\u00adte es wort\u00adlos weg. Ich biss die Z\u00e4h\u00adne zusammen.<\/p><p>Die Erin\u00adne\u00adrung ist schon manch\u00admal ein arger Schalk. Hin\u00adter jeder Stra\u00ad\u00dfen\u00adecke ver\u00admu\u00adte\u00adte ich den USV-Sport\u00adplatz. Ich wei\u00df nicht mehr, wie oft ich mir sicher war.<\/p><p>Das War\u00adum-Schei\u00ad\u00dfer\u00adchen nin\u00adgel\u00adte auch schon wie\u00adder. Auch die ande\u00adren Macken und Fim\u00admel, die w\u00e4h\u00adrend der letz\u00adte 24 Stun\u00adden mei\u00adne Stim\u00admung hoch und run\u00adter regel\u00adten, begehr\u00adten noch ein\u00admal Auf\u00admerk\u00adsam\u00adkeit. Nicht eine Lau\u00adne konn\u00adte ich beim Wan\u00addern absch\u00fct\u00adteln. Von wegen Seelenreinigung.<\/p><p>Letzt\u00adend\u00adlich haben sie mich bis hier\u00adher beglei\u00adtet, gedr\u00e4ngt und gef\u00fchrt. Fakt: Sie geh\u00f6\u00adren zu&nbsp;mir!<\/p><p>Es geht doch nicht dar\u00adum, etwas zu ver\u00adlie\u00adren, son\u00addern etwas zu gewinnen.<\/p><p>Hal\u00adle\u00adlu\u00adja Phra\u00adsen\u00adschwein! Du also auch&nbsp;noch!<\/p><p>Lars war ste\u00adhen geblie\u00adben. Dies\u00admal hat\u00adte ich mich nicht get\u00e4uscht: Das Tor zum USV-Gel\u00e4nde.<\/p><p><span class=\"dquo\">\u201e<\/span>Nie wie\u00adder!\u201c schwo\u00adren wir uns in die\u00adsem Augen\u00adblick. Und wir mein\u00adten es so. Und wir grins\u00adten&nbsp;dabei.<\/p><p>Alle Stra\u00adpa\u00adzen und Bles\u00adsu\u00adren waren augen\u00adblick\u00adlich ver\u00adges\u00adsen. Eitel-Son\u00adnen\u00adschein strahl\u00adte mir aus dem Hin\u00adtern. Wie gern h\u00e4t\u00adte ich mir die Sekun\u00adden eingeweckt.<\/p><p>Am Ziel stan\u00adden Kat\u00adja und Andr\u00e9 und Tuti. Er hat\u00adte nach sei\u00adnem Gang noch ein\u00admal drei\u00adein\u00adhalb Stun\u00adden auf uns gewar\u00adtet. Ohne&nbsp;Worte.<\/p><p>Mehr\u00adfach hat\u00adte ich mir w\u00e4h\u00adrend des Marschs Ziel\u00adge\u00adra\u00adden\u00adschw\u00e4r\u00adme\u00adrei\u00aden ange\u00adh\u00f6rt. Nur so viel: Wir lie\u00ad\u00dfen uns Zeit. Viel Zeit. Obwohl die Freun\u00adde mit Bier\u00adfla\u00adschen winkten.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdebda5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdebda5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-b293065\" data-id=\"b293065\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e537f70 elementor-widget elementor-widget-text-editor\" data-id=\"e537f70\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"caps\">PS<\/span> I: Auf der R\u00fcck\u00adfahrt sorg\u00adte ich mit dem Vor\u00adschlag, noch ein Kneip\u00adchen in Erfurt auf\u00adzu\u00adsu\u00adchen, f\u00fcr Am\u00fc\u00adse\u00adment. Kurz dar\u00adauf: Blitzschlaf.<\/p><p><span class=\"caps\">PS<\/span> <span class=\"caps\">II<\/span>: Am 29. Mai 2015 ver\u00adl\u00e4uft die Hori\u00adzon\u00adta\u00adle in die ent\u00adge\u00adgen\u00adge\u00adsetz\u00adte Rich\u00adtung. Ich wer\u00adde mir den Gang schen\u00adken. Ein Anlass fin\u00addet sich. Tut\u00adti und Lars, erwi\u00adder\u00adten dies\u00adbe\u00adz\u00fcg\u00adlich auf mei\u00adne vor\u00adsich\u00adti\u00adge Fra\u00adge, dum\u00adme&nbsp;Frage.<\/p><p><span class=\"caps\">PS<\/span> <span class=\"caps\">III<\/span>: Das letz\u00adte Wort gilt allen Orga\u00adni\u00adsa\u00adto\u00adren und Hel\u00adfern der Hori\u00adzon\u00adta\u00adle:&nbsp;Danke!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d4dd6ae\" data-id=\"d4dd6ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6405c95 elementor-widget elementor-widget-image-gallery\" data-id=\"6405c95\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id=\"gallery-5\" class=\"gallery galleryid-149 gallery-columns-1 gallery-size-thumbnail\"><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon portrait\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6405c95\" data-elementor-lightbox-title=\"img_2669\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg3LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvaW1nXzI2NjkuanBnIiwic2xpZGVzaG93IjoiNjQwNWM5NSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/img_2669.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/img_2669-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><figure class=\"gallery-item\">\n\t\t\t<div class=\"gallery-icon landscape\">\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6405c95\" data-elementor-lightbox-title=\"img_2665\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg2LCJ1cmwiOiJodHRwczpcL1wvaGFzZW5qYWdkLmFubmFrcmFtLmRlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wM1wvaW1nXzI2NjUuanBnIiwic2xpZGVzaG93IjoiNjQwNWM5NSJ9\" href=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/img_2665.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hasenjagd.annakram.de\/wp-content\/uploads\/2019\/03\/img_2665-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt><\/a>\n\t\t\t<\/div><\/figure><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wir hat\u00adten das Basis\u00adla\u00adger, die Jena\u00ader USV-Spor\u00adt\u00adhal\u00ad\u00adle an den Teu\u00adfels\u00adl\u00f6\u00adchern, erreicht. Der Name des Orts lie\u00df eine fana\u00adti\u00adsche Hor\u00adde Wol\u00adf\u00ad\u00adgang-Petry-J\u00fcn\u00ad\u00adger, die Apo\u00adka\u00adlyp\u00adse beschw\u00f6\u00adrend,&nbsp;vor mei\u00adnem inne\u00adren Auge auf\u00adtau\u00adchen. \u201cH\u00f6l\u00adle! H\u00f6l\u00adle!\u201d&nbsp;Ich hat\u00adte mich im&nbsp;Griff. Knapp tau\u00adsend Sports\u00adm\u00e4n\u00adner und \u2011frau\u00aden nebst Anhang hat\u00adten sich ein\u00adge\u00adfun\u00adden.&nbsp;Das Org-Team hat\u00adte Bier\u00adgar\u00adni\u00adtu\u00adren und Unter\u00adhal\u00adtungs\u00admu\u00adsik besorgt. Ein&nbsp;paar der weni\u00adgen frei\u00aden Pl\u00e4t\u00adze konn\u00adten&nbsp;wir&nbsp;[\u2026]<\/p>\n","protected":false},"author":2,"featured_media":257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[9],"tags":[],"class_list":["post-149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tagebuch","entry","has-media"],"_links":{"self":[{"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/posts\/149"}],"collection":[{"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":31,"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/posts\/149\/revisions"}],"predecessor-version":[{"id":290,"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/posts\/149\/revisions\/290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/media\/257"}],"wp:attachment":[{"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/media?parent=149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/categories?post=149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hasenjagd.annakram.de\/en\/wp-json\/wp\/v2\/tags?post=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}